

{"id":10221,"date":"2022-11-07T14:00:10","date_gmt":"2022-11-07T13:00:10","guid":{"rendered":"https:\/\/www.oc.com.tn\/?p=10221"},"modified":"2022-11-07T14:06:43","modified_gmt":"2022-11-07T13:06:43","slug":"location-de-quelques-centres-de-collecte-de-loffice-des-cereales","status":"publish","type":"post","link":"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/","title":{"rendered":"Location de quelques centres de collecte de l&#8217;Office des c\u00e9r\u00e9ales"},"content":{"rendered":"\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"http:\/\/www.oc.com.tn\/wp-content\/uploads\/2022\/11\/\u0627\u0639\u0644\u0627\u0646-24-2022.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">  T\u00e9l\u00e9charger PDF  <\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[80,100],"tags":[],"class_list":["post-10221","post","type-post","status-publish","format-standard","hentry","category-avis-et-annonces","category-avis-et-annonces-ar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Location de quelques centres de collecte de l&#039;Office des c\u00e9r\u00e9ales - Office des C\u00e9r\u00e9ales - Tunisie<\/title>\n<meta name=\"description\" content=\"Office des C\u00e9r\u00e9ales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Location de quelques centres de collecte de l&#039;Office des c\u00e9r\u00e9ales - Office des C\u00e9r\u00e9ales - Tunisie\" \/>\n<meta property=\"og:description\" content=\"Office des C\u00e9r\u00e9ales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/\" \/>\n<meta property=\"og:site_name\" content=\"Office des C\u00e9r\u00e9ales - Tunisie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100069933501880\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-07T13:00:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-07T13:06:43+00:00\" \/>\n<meta name=\"author\" content=\"tender\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"tender\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/\"},\"author\":{\"name\":\"tender\",\"@id\":\"https:\/\/www.oc.com.tn\/fr\/#\/schema\/person\/7d67e98c12dbea10942a0f7988e7f7ac\"},\"headline\":\"Location de quelques centres de collecte de l&#8217;Office des c\u00e9r\u00e9ales\",\"datePublished\":\"2022-11-07T13:00:10+00:00\",\"dateModified\":\"2022-11-07T13:06:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/\"},\"wordCount\":16,\"publisher\":{\"@id\":\"https:\/\/www.oc.com.tn\/fr\/#organization\"},\"articleSection\":[\"Avis et Annonces\",\"Avis et Annonces\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/\",\"url\":\"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/\",\"name\":\"Location de quelques centres de collecte de l'Office des c\u00e9r\u00e9ales - Office des C\u00e9r\u00e9ales - Tunisie\",\"isPartOf\":{\"@id\":\"https:\/\/www.oc.com.tn\/fr\/#website\"},\"datePublished\":\"2022-11-07T13:00:10+00:00\",\"dateModified\":\"2022-11-07T13:06:43+00:00\",\"description\":\"Office des C\u00e9r\u00e9ales\",\"breadcrumb\":{\"@id\":\"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.oc.com.tn\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Location de quelques centres de collecte de l&rsquo;Office des c\u00e9r\u00e9ales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.oc.com.tn\/fr\/#website\",\"url\":\"https:\/\/www.oc.com.tn\/fr\/\",\"name\":\"Office des C\u00e9r\u00e9ales - Tunisie\",\"description\":\"Office des C\u00e9r\u00e9ales - Tunisie\",\"publisher\":{\"@id\":\"https:\/\/www.oc.com.tn\/fr\/#organization\"},\"alternateName\":\"Office des C\u00e9r\u00e9ales - Tunisie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.oc.com.tn\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.oc.com.tn\/fr\/#organization\",\"name\":\"Office des C\u00e9r\u00e9ales - Tunisie\",\"url\":\"https:\/\/www.oc.com.tn\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.oc.com.tn\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.oc.com.tn\/wp-content\/uploads\/2020\/07\/Logo.png\",\"contentUrl\":\"https:\/\/www.oc.com.tn\/wp-content\/uploads\/2020\/07\/Logo.png\",\"width\":47,\"height\":74,\"caption\":\"Office des C\u00e9r\u00e9ales - Tunisie\"},\"image\":{\"@id\":\"https:\/\/www.oc.com.tn\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100069933501880\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.oc.com.tn\/fr\/#\/schema\/person\/7d67e98c12dbea10942a0f7988e7f7ac\",\"name\":\"tender\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.oc.com.tn\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/61d83a4ac29a23ca8e4f6724b2138881ea510fe08034853f92679db97b103b3d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/61d83a4ac29a23ca8e4f6724b2138881ea510fe08034853f92679db97b103b3d?s=96&d=mm&r=g\",\"caption\":\"tender\"},\"url\":\"https:\/\/www.oc.com.tn\/fr\/author\/tender\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Location de quelques centres de collecte de l'Office des c\u00e9r\u00e9ales - Office des C\u00e9r\u00e9ales - Tunisie","description":"Office des C\u00e9r\u00e9ales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/","og_locale":"fr_FR","og_type":"article","og_title":"Location de quelques centres de collecte de l'Office des c\u00e9r\u00e9ales - Office des C\u00e9r\u00e9ales - Tunisie","og_description":"Office des C\u00e9r\u00e9ales","og_url":"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/","og_site_name":"Office des C\u00e9r\u00e9ales - Tunisie","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100069933501880","article_published_time":"2022-11-07T13:00:10+00:00","article_modified_time":"2022-11-07T13:06:43+00:00","author":"tender","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"tender","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/#article","isPartOf":{"@id":"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/"},"author":{"name":"tender","@id":"https:\/\/www.oc.com.tn\/fr\/#\/schema\/person\/7d67e98c12dbea10942a0f7988e7f7ac"},"headline":"Location de quelques centres de collecte de l&#8217;Office des c\u00e9r\u00e9ales","datePublished":"2022-11-07T13:00:10+00:00","dateModified":"2022-11-07T13:06:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/"},"wordCount":16,"publisher":{"@id":"https:\/\/www.oc.com.tn\/fr\/#organization"},"articleSection":["Avis et Annonces","Avis et Annonces"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/","url":"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/","name":"Location de quelques centres de collecte de l'Office des c\u00e9r\u00e9ales - Office des C\u00e9r\u00e9ales - Tunisie","isPartOf":{"@id":"https:\/\/www.oc.com.tn\/fr\/#website"},"datePublished":"2022-11-07T13:00:10+00:00","dateModified":"2022-11-07T13:06:43+00:00","description":"Office des C\u00e9r\u00e9ales","breadcrumb":{"@id":"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.oc.com.tn\/fr\/location-de-quelques-centres-de-collecte-de-loffice-des-cereales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.oc.com.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Location de quelques centres de collecte de l&rsquo;Office des c\u00e9r\u00e9ales"}]},{"@type":"WebSite","@id":"https:\/\/www.oc.com.tn\/fr\/#website","url":"https:\/\/www.oc.com.tn\/fr\/","name":"Office des C\u00e9r\u00e9ales - Tunisie","description":"Office des C\u00e9r\u00e9ales - Tunisie","publisher":{"@id":"https:\/\/www.oc.com.tn\/fr\/#organization"},"alternateName":"Office des C\u00e9r\u00e9ales - Tunisie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oc.com.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.oc.com.tn\/fr\/#organization","name":"Office des C\u00e9r\u00e9ales - Tunisie","url":"https:\/\/www.oc.com.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.oc.com.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.oc.com.tn\/wp-content\/uploads\/2020\/07\/Logo.png","contentUrl":"https:\/\/www.oc.com.tn\/wp-content\/uploads\/2020\/07\/Logo.png","width":47,"height":74,"caption":"Office des C\u00e9r\u00e9ales - Tunisie"},"image":{"@id":"https:\/\/www.oc.com.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100069933501880"]},{"@type":"Person","@id":"https:\/\/www.oc.com.tn\/fr\/#\/schema\/person\/7d67e98c12dbea10942a0f7988e7f7ac","name":"tender","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.oc.com.tn\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/61d83a4ac29a23ca8e4f6724b2138881ea510fe08034853f92679db97b103b3d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61d83a4ac29a23ca8e4f6724b2138881ea510fe08034853f92679db97b103b3d?s=96&d=mm&r=g","caption":"tender"},"url":"https:\/\/www.oc.com.tn\/fr\/author\/tender\/"}]}},"_links":{"self":[{"href":"https:\/\/www.oc.com.tn\/fr\/wp-json\/wp\/v2\/posts\/10221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oc.com.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oc.com.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oc.com.tn\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oc.com.tn\/fr\/wp-json\/wp\/v2\/comments?post=10221"}],"version-history":[{"count":11,"href":"https:\/\/www.oc.com.tn\/fr\/wp-json\/wp\/v2\/posts\/10221\/revisions"}],"predecessor-version":[{"id":10250,"href":"https:\/\/www.oc.com.tn\/fr\/wp-json\/wp\/v2\/posts\/10221\/revisions\/10250"}],"wp:attachment":[{"href":"https:\/\/www.oc.com.tn\/fr\/wp-json\/wp\/v2\/media?parent=10221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oc.com.tn\/fr\/wp-json\/wp\/v2\/categories?post=10221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oc.com.tn\/fr\/wp-json\/wp\/v2\/tags?post=10221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}